{"id":6328,"date":"2019-02-27T13:27:19","date_gmt":"2019-02-27T13:27:19","guid":{"rendered":"https:\/\/www.gruber-logistics.com\/informativa-cookie\/"},"modified":"2025-04-22T12:23:42","modified_gmt":"2025-04-22T12:23:42","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/","title":{"rendered":"Cookie policy"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_margin=&#8220;default&#8220; bg_image=&#8220;3693&#8243; bg_position=&#8220;center center&#8220; bg_repeat=&#8220;no-repeat&#8220; bg_color=&#8220;#333333&#8243; scene_position=&#8220;center&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; top_padding=&#8220;23%&#8220; bottom_padding=&#8220;2%&#8220; color_overlay=&#8220;#161616&#8243; overlay_strength=&#8220;0.5&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; video_mute=&#8220;true&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_custom_heading text=&#8220;Cookie policy&#8220; font_container=&#8220;tag:h1|text_align:left&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; column_margin=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column centered_text=&#8220;true&#8220; column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;0.8&#8243; background_hover_color_opacity=&#8220;1&#8243; font_color=&#8220;#ffffff&#8220; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<div class=\"one_line_col\">\n<h2>Cookie Policy von www.gruber-logistics.com\/<\/h2>\n<p>Dieses Dokument enth\u00e4lt Informationen \u00fcber die Technologien, die es dieser Anwendung erm\u00f6glichen, die unten beschriebenen Zwecke zu erreichen. Diese Technologien erm\u00f6glichen es dem Eigent\u00fcmer, Informationen zu sammeln und zu speichern (z. B. durch die Verwendung von Cookies) oder Ressourcen (z. B. durch die Ausf\u00fchrung eines Skripts) auf dem Ger\u00e4t des Nutzers zu verwenden, wenn der Nutzer mit dieser Anwendung interagiert.<br \/>\nDer Einfachheit halber werden diese Technologien in diesem Dokument kurz als Tracking Tools\u201c bezeichnet, es sei denn, es besteht Grund zur Differenzierung.<br \/>\nObwohl beispielsweise Cookies sowohl in Web- als auch in mobilen Browsern verwendet werden k\u00f6nnen, w\u00e4re es unangemessen, im Zusammenhang mit mobilen Anwendungen von Cookies zu sprechen, da es sich um Tracking-Tools handelt, die das Vorhandensein eines Browsers erfordern. Aus diesem Grund wird der Begriff \u201eCookie\u201c in diesem Dokument nur verwendet, wenn er sich speziell auf diese Art von Tracking-Tool bezieht.<\/p>\n<p>Einige der Zwecke, f\u00fcr die Tracking-Tools verwendet werden, k\u00f6nnen auch die Zustimmung des Nutzers erfordern. Wenn die Zustimmung erteilt wurde, kann sie jederzeit frei widerrufen werden, indem die in diesem Dokument enthaltenen Anweisungen befolgt werden.<br \/>\nDiese Anwendung verwendet Tracking-Tools, die direkt vom Eigent\u00fcmer verwaltet werden (gemeinhin als \u201eErstanbieter\u201c-Tracking-Tools bezeichnet), und Tracking-Tools, die von Dritten bereitgestellte Dienste erm\u00f6glichen (gemeinhin als \u201eDrittanbieter\u201c-Tracking-Tools bezeichnet). Sofern in diesem Dokument nicht anders angegeben, haben diese Dritten Zugriff auf ihre jeweiligen Tracking-Tools.<br \/>\nDauer und Ablauf von Cookies und anderen \u00e4hnlichen Tracking-Tools k\u00f6nnen variieren, je nachdem, was von dem f\u00fcr die Verarbeitung Verantwortlichen oder dem jeweiligen Drittanbieter festgelegt wurde. Einige von ihnen verfallen am Ende der Browsersitzung des Nutzers.<br \/>\nZus\u00e4tzlich zu den Angaben in der nachstehenden Beschreibung der einzelnen Kategorien k\u00f6nnen die Nutzer detailliertere und aktuellere Informationen \u00fcber die Dauer sowie andere relevante Informationen &#8211; wie das Vorhandensein anderer Tracking-Tools &#8211; in den Datenschutzerkl\u00e4rungen der jeweiligen Drittanbieter (\u00fcber die angegebenen Links) oder durch Kontaktaufnahme mit dem f\u00fcr die Verarbeitung Verantwortlichen erhalten.<\/p>\n<h2>Wie diese Anwendung Tracking-Tools verwendet<\/h2>\n<h3>Erforderlich<\/h3>\n<p>Diese Anwendung verwendet Cookies, die gemeinhin als \u201etechnische\u201c oder \u00e4hnliche Tracking-Tools bezeichnet werden, um Aktivit\u00e4ten durchzuf\u00fchren, die unbedingt erforderlich sind, um den Betrieb oder die Bereitstellung des Dienstes zu gew\u00e4hrleisten.<\/p>\n<h4>Von Dritten betriebene Tracking-Tools<\/h4>\n<h3 class=\"w_icon_24 policyicon_purpose_11180670 iub-purpose iub-purpose-11180670\">Cloudflare (Cloudflare Inc.)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Cloudflare ist ein Dienst zur Optimierung und Verteilung des Datenverkehrs, der von Cloudflare Inc. bereitgestellt wird. Die Art und Weise, wie Cloudflare integriert ist, bedeutet, dass es den gesamten Datenverkehr dieser Anwendung filtert, d. h. die Kommunikation zwischen dieser Anwendung und dem Browser des Nutzers, und auch die Erfassung statistischer Daten dar\u00fcber erm\u00f6glicht.<br \/>\nVerarbeitete personenbezogene Daten: Tracking-Tools und verschiedene Arten von Daten, wie in der Datenschutzrichtlinie des Dienstes angegeben.<br \/>\nOrt der Verarbeitung: USA \u2013 <a href=\"https:\/\/www.cloudflare.com\/privacypolicy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<\/div>\n<\/div>\n<h3 class=\"w_icon_24 policyicon_purpose_11180674 iub-purpose iub-purpose-11180674\">Google reCAPTCHA (Google LLC)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Google reCAPTCHA ist ein Dienst zum Schutz vor SPAM, der von Google LLC bereitgestellt wird. Die Nutzung des reCAPTCHA-Systems unterliegt den <a href=\"https:\/\/www.google.com\/intl\/it\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">privacy policy<\/a> und die <a href=\"https:\/\/www.google.com\/intl\/it\/policies\/terms\/\" target=\"_blank\" rel=\"noopener\">Benutzungsbedingungen<\/a> von Google.<\/p>\n<p>Weitere Informationen \u00fcber die Verwendung von Daten durch Google finden Sie in der <a href=\"https:\/\/policies.google.com\/technologies\/partner-sites?hl=it\" target=\"_blank\" rel=\"noopener\">partner policy<\/a> und ihre <a href=\"https:\/\/business.safety.google\/intl\/it\/privacy\/\">Seite Kommerzielle Daten<\/a>.<\/p>\n<\/div>\n<p>Verarbeitete personenbezogene Daten: Klicks, Nutzungsdaten, Tastendruckereignisse, Bewegungssensorereignisse, Ber\u00fchrungsereignisse, Mausbewegungen, Bildlaufposition, Antworten auf Fragen und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: USA \u2013 <a href=\"https:\/\/business.safety.google\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<p>Dauer der Lagerung:<\/p>\n<ul>\n<li>_GRECAPTCHA: Sitzungsdauer<\/li>\n<li>rc::a: nicht definiert<\/li>\n<li>rc::b: Sitzungsdauer<\/li>\n<li>rc::c: Sitzungsdauer<\/li>\n<\/ul>\n<\/div>\n<h3 class=\"w_icon_24 policyicon_purpose_11180675 iub-purpose iub-purpose-11180675\">Google Tag Manager (Google LLC)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Google Tag Manager ist ein Tag-Management-Dienst, der von Google LLC bereitgestellt wird.<\/p>\n<p>Weitere Informationen \u00fcber die Datennutzung durch Google finden Sie in den <a href=\"https:\/\/policies.google.com\/technologies\/partner-sites\">Partner-Richtlinien<\/a> und auf der <a href=\"https:\/\/business.safety.google\/privacy\/\">Seite f\u00fcr kommerzielle Daten<\/a>.<\/p>\n<\/div>\n<p>Verarbeitete pers\u00f6nliche Daten: Nutzungsdaten und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: Vereinigte Staaten \u2013 <a href=\"https:\/\/business.safety.google\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<\/div>\n<h3>Erfahrung<\/h3>\n<p>Diese Anwendung verwendet Tracking Tools, um die Qualit\u00e4t der Benutzererfahrung zu verbessern und Interaktionen mit externen Inhalten, Netzwerken und Plattformen zu erm\u00f6glichen.<\/p>\n<h4>Von Dritten betriebene Tracking-Tools<\/h4>\n<h3 class=\"w_icon_24 policyicon_purpose_11180671 iub-purpose iub-purpose-11180671\">Font Awesome (Fonticons, Inc. )<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Font Awesome ist ein von Fonticons, Inc. betriebener Dienst zur Anzeige von Schriftstilen, der es dieser Anwendung erm\u00f6glicht, solche Inhalte in ihre Seiten zu integrieren.<\/p>\n<p>Verarbeitete personenbezogene Daten: Nutzungsdaten und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: Vereinigte Staaten &#8211; <a href=\"https:\/\/fontawesome.com\/privacy\">Datenschutzrichtlinie<\/a>.<\/p>\n<\/div>\n<\/div>\n<h3 class=\"w_icon_24 policyicon_purpose_11180673 iub-purpose iub-purpose-11180673\">Google Fonts (Google LLC)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Google Fonts ist ein von Google LLC betriebener Dienst zur Anzeige von Schriftarten, der es dieser Anwendung erm\u00f6glicht, solche Inhalte in ihre Seiten zu integrieren.<\/p>\n<p>Verarbeitete personenbezogene Daten: Nutzungsdaten und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: Vereinigte Staaten &#8211; <a href=\"https:\/\/business.safety.google\/privacy\/\">Datenschutzbestimmungen<\/a>.<\/p>\n<\/div>\n<\/div>\n<h3>Anmeldung beim Facebook-Konto (Meta Platforms, Inc.)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Dieser Dienst erm\u00f6glicht es dieser Anwendung, sich mit dem Konto des Benutzers im sozialen Netzwerk Facebook zu verbinden, das von Meta Platforms, Inc. bereitgestellt wird.<\/p>\n<p>Erforderliche Berechtigungen: Nutzungsdaten, E-Mail, Ger\u00e4teinformationen und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: Vereinigte Staaten \u2013 <a href=\"https:\/\/www.facebook.com\/privacy\/policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.facebook.com\/help\/247395082112892\" target=\"_blank\" rel=\"noopener\">Opt out<\/a>.<\/p>\n<\/div>\n<p>Dauer der Speicherung:<\/p>\n<ul>\n<li>_fbp: 3 Monate<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n<h3>Facebook-Like-Schaltfl\u00e4che und soziale Widgets (Meta Platforms, Inc.)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Die Facebook-Schaltfl\u00e4che \u201eGef\u00e4llt mir\u201c und die sozialen Widgets sind Dienste zur Interaktion mit dem sozialen Netzwerk Facebook, die von Meta Platforms, Inc. bereitgestellt werden.<\/p>\n<p>Verarbeitete personenbezogene Daten: Nutzungsdaten und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: Vereinigte Staaten &#8211; <a href=\"\u201ehttps:\/\/www.facebook.com\/privacy\/policy\/\u201c\">Privacy Policy<\/a> &#8211; <a href=\"\u201ehttps:\/\/www.facebook.com\/help\/247395082112892\u201c\">Opt out<\/a>.<\/p>\n<p>Dauer der Speicherung:<\/p>\n<ul>\n<li>_fbp: 3 Monate<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<h3>Messung<\/h3>\n<p>Diese Anwendung verwendet Tracking Tools, um den Datenverkehr zu messen und das Verhalten der Nutzer zu analysieren, um den Dienst zu verbessern.<\/p>\n<h4>Von Dritten betriebene Tracking-Tools<\/h4>\n<h3 class=\"w_icon_24 policyicon_purpose_11180672 iub-purpose iub-purpose-11180672\">Google Analytics 4 (Google LLC)<\/h3>\n<div class=\"details_body\">\n<div class=\"wrap\">\n<p>Google Analytics ist ein Statistikdienst, der von Google LLC (\u201eGoogle\u201c) bereitgestellt wird. Google verwendet die erfassten personenbezogenen Daten, um die Nutzung dieser Anwendung zu verfolgen und zu untersuchen, Berichte zu erstellen und diese mit anderen von Google entwickelten Diensten zu teilen. Google kann personenbezogene Daten verwenden, um Anzeigen in seinem Werbenetzwerk zu kontextualisieren und zu personalisieren. In Google Analytics 4 werden die IP-Adressen zum Zeitpunkt der Erfassung verwendet und anschlie\u00dfend gel\u00f6scht, bevor die Daten in einem Datenzentrum oder auf einem Server gespeichert werden. Weitere Informationen finden Sie in <a href=\"https:\/\/support.google.com\/analytics\/answer\/12017362?hl=it&amp;ref_topic=2919631\">der offiziellen Dokumentation von Google<\/a>.<\/p>\n<p>Weitere Informationen \u00fcber die Verwendung von Daten durch Google finden Sie in den <a href=\"\u201ehttps:\/\/policies.google.com\/technologies\/partner-sites\u201c\">Partner-Richtlinien<\/a> und auf der <a href=\"\u201ehttps:\/\/business.safety.google\/privacy\/\u201c\">Seite Gesch\u00e4ftsdaten<\/a>.<\/p>\n<p>Verarbeitete personenbezogene Daten: Nutzungsdaten, Anzahl der Nutzer, Sitzungsstatistiken und Tracking-Tools.<\/p>\n<p>Ort der Verarbeitung: Vereinigte Staaten &#8211; <a href=\"\u201ehttps:\/\/business.safety.google\/privacy\/\u201c\">Privacy Policy<\/a> &#8211; <a href=\"\u201ehttps:\/\/tools.google.com\/dlpage\/gaoptout?hl=it\u201c\">Opt Out<\/a>.<\/p>\n<p>Dauer der Speicherung:<\/p>\n<ul>\n<li>_ga: 2 Jahre<\/li>\n<li>_ga_*: 2 Jahre<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<h3>Verwaltung der Pr\u00e4ferenzen und Erteilung oder Widerruf der Zustimmung in dieser Anwendung<\/h3>\n<p>Wenn die Verwendung von Trackern auf einer Einwilligung beruht, k\u00f6nnen die Nutzer diese Einwilligung erteilen oder widerrufen, indem sie ihre Pr\u00e4ferenzen \u00fcber das entsprechende, in dieser Anwendung verf\u00fcgbare Panel f\u00fcr Datenschutzeinstellungen festlegen oder aktualisieren.<br \/>\nWas die Tracking-Tools Dritter betrifft, so k\u00f6nnen die Nutzer ihre Pr\u00e4ferenzen verwalten, indem sie den entsprechenden Opt-Out-Link (falls vorhanden) besuchen, die in der Datenschutzrichtlinie des Dritten beschriebenen Tools nutzen oder sich direkt an diesen wenden.<\/p>\n<h4>Wie Sie Cookies und \u00e4hnliche Technologien \u00fcber Ihre Ger\u00e4teeinstellungen kontrollieren oder l\u00f6schen k\u00f6nnen<\/h4>\n<p>Benutzer k\u00f6nnen ihre Browsereinstellungen verwenden, um:<\/p>\n<ul>\n<li>Sehen, welche Cookies oder \u00e4hnliche Technologien auf dem Ger\u00e4t gesetzt wurden;<\/li>\n<li>Cookies oder \u00e4hnliche Technologien blockieren;<\/li>\n<li>Cookies oder \u00e4hnliche Technologien aus dem Browser l\u00f6schen.<\/li>\n<\/ul>\n<p>Die Browsereinstellungen erlauben jedoch keine granulare Kontrolle der Zustimmung nach Kategorien.<\/p>\n<p>Informationen zur Verwaltung von Cookies in den g\u00e4ngigsten Browsern finden Sie beispielsweise unter folgenden Adressen:<\/p>\n<ul>\n<li><a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=it&amp;p=cpn_cookies\" target=\"_blank\" rel=\"noopener nofollow\">Google Chrome<\/a><\/li>\n<li><a href=\"https:\/\/support.mozilla.org\/it\/kb\/Attivare%20e%20disattivare%20i%20cookie\" target=\"_blank\" rel=\"noopener nofollow\">Mozilla Firefox<\/a><\/li>\n<li><a href=\"https:\/\/support.apple.com\/it-it\/guide\/safari\/manage-cookies-and-website-data-sfri11471\/\" target=\"_blank\" rel=\"noopener nofollow\">Apple Safari<\/a><\/li>\n<li><a href=\"http:\/\/windows.microsoft.com\/it-it\/windows-vista\/block-or-allow-cookies\" target=\"_blank\" rel=\"noopener nofollow\">Microsoft Internet Explorer<\/a><\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/it-it\/help\/4027947\" target=\"_blank\" rel=\"noopener nofollow\">Microsoft Edge<\/a><\/li>\n<li><a href=\"https:\/\/support.brave.com\/hc\/articles\/360022806212-How-do-I-use-Shields-while-browsing\" target=\"_blank\" rel=\"noopener nofollow\">Brave<\/a><\/li>\n<li><a href=\"https:\/\/help.opera.com\/latest\/web-preferences\/#cookies\" target=\"_blank\" rel=\"noopener nofollow\">Opera<\/a><\/li>\n<\/ul>\n<p>Die Nutzer k\u00f6nnen auch bestimmte Tracking-Tools f\u00fcr mobile Anwendungen verwalten, indem sie diese \u00fcber die entsprechenden Ger\u00e4teeinstellungen deaktivieren, z. B. \u00fcber die Einstellungen f\u00fcr mobile Werbung oder die Tracking-Einstellungen im Allgemeinen (die Nutzer k\u00f6nnen die entsprechenden Einstellungen in ihren Ger\u00e4teeinstellungen finden).<\/p>\n<h4>Folgen der Weigerung, Tracking-Tools zu verwenden<\/h4>\n<p>Es steht den Nutzern frei zu entscheiden, ob sie die Verwendung von Tracking Tools zulassen wollen oder nicht. Bitte beachten Sie jedoch, dass die Tracking-Tools diese Anwendung in die Lage versetzen, den Nutzern ein besseres Erlebnis und erweiterte Funktionen zu bieten (im Einklang mit den in diesem Dokument beschriebenen Zwecken). Wenn der Nutzer beschlie\u00dft, die Verwendung von Tracking-Tools zu blockieren, ist der Eigent\u00fcmer daher m\u00f6glicherweise nicht in der Lage, die entsprechenden Funktionen bereitzustellen.<\/p>\n<h3>Datenkontrolleur<\/h3>\n<p>GRUBER Logistics S.p.A.<br \/>\nEingetragener Sitz: Via Nazionale 75, I-39040 Ora (BZ)<br \/>\nSteuernummer, VAT und Handelsregister von Bozen: IT00520690215<\/p>\n<p><strong>E-Mail Adresse des Inhabers<\/strong><strong>:<\/strong>\u00a0marketing@gruber-logistics.com<\/p>\n<p>Da die Verwendung von Tracking-Tools von Dritten in dieser Anwendung nicht vollst\u00e4ndig vom Eigent\u00fcmer kontrolliert werden kann, ist jeder spezifische Verweis auf Tracking-Tools von Dritten nur als Hinweis zu verstehen. Um vollst\u00e4ndige Informationen zu erhalten, werden die Nutzer gebeten, die Datenschutzbestimmungen der jeweiligen in diesem Dokument aufgef\u00fchrten Drittanbieterdienste zu konsultieren.<br \/>\nIn Anbetracht der objektiven Komplexit\u00e4t der Identifizierung von Tracking-Technologien werden die Nutzer gebeten, sich mit dem Eigent\u00fcmer in Verbindung zu setzen, wenn sie weitere Informationen \u00fcber die Verwendung solcher Technologien in dieser Anwendung erhalten m\u00f6chten.<\/p>\n<\/div>\n<div class=\"one_line_col\">\n<div class=\"box_primary box_10 definitions expand expanded\">\n<h3>Definitionen und rechtliche Hinweise<\/h3>\n<div class=\"expand-content\">\n<h4>Personenbezogene Daten (oder Daten)<\/h4>\n<p>Personenbezogene Daten sind alle Informationen, die direkt oder indirekt, auch in Verbindung mit anderen Informationen, einschlie\u00dflich einer pers\u00f6nlichen Identifikationsnummer, eine nat\u00fcrliche Person identifizierbar oder identifizierbar machen.<\/p>\n<h4>Verwendungsdaten<\/h4>\n<p>Dabei handelt es sich um die Informationen, die automatisch \u00fcber diese Anwendung (einschlie\u00dflich der in diese Anwendung integrierten Anwendungen Dritter) erfasst werden, darunter: IP-Adressen oder Dom\u00e4nennamen der Computer, die vom Nutzer verwendet werden, der eine Verbindung zu dieser Anwendung herstellt, URI (Uniform Resource Identifier)-Notationsadressen, die Uhrzeit der Anfrage, die zur Weiterleitung der Anfrage an den Server verwendete Methode, die Gr\u00f6\u00dfe der als Antwort erhaltenen Datei, der Zahlencode, der den Status der Serverantwort angibt (erfolgreich, Fehler usw.), das Herkunftsland, die Merkmale des vom Besucher verwendeten Browsers und Betriebssystems, die verschiedenen zeitlichen Zusammenh\u00e4nge des Besuchs (z. B. die auf jeder Seite verbrachte Zeit) und Einzelheiten der vom Nutzer verfolgten Reiseroute. ) das Herkunftsland, die Merkmale des vom Besucher verwendeten Browsers und des Betriebssystems, die verschiedenen zeitlichen Aspekte des Besuchs (z. B. die auf jeder Seite verbrachte Zeit) und die Einzelheiten der innerhalb der Anwendung zur\u00fcckgelegten Strecke, insbesondere die Reihenfolge der aufgerufenen Seiten, die Parameter des Betriebssystems und die Computerumgebung des Benutzers.<\/p>\n<h4>Benutzer<\/h4>\n<p>Die Person, die diese Anwendung nutzt und die, sofern nicht anders angegeben, die betroffene Person ist.<\/p>\n<h4>Betroffene Person<\/h4>\n<p>Die nat\u00fcrliche Person, auf die sich die personenbezogenen Daten beziehen.<\/p>\n<h4>Bearbeiter (oder Manager)<\/h4>\n<p>Die nat\u00fcrliche Person, die juristische Person, die \u00f6ffentliche Verwaltung und jede andere Stelle, die personenbezogene Daten im Auftrag des f\u00fcr die Verarbeitung Verantwortlichen verarbeitet, wie in dieser Datenschutzrichtlinie dargelegt.<\/p>\n<h4>Datenverantwortlicher (oder Eigent\u00fcmer)<\/h4>\n<p>Die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Dienststelle oder sonstige Einrichtung, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung personenbezogener Daten sowie \u00fcber die eingesetzten Instrumente, einschlie\u00dflich der Sicherheitsma\u00dfnahmen im Zusammenhang mit dem Betrieb und der Nutzung dieser Anwendung, entscheidet. Der f\u00fcr die Datenverarbeitung Verantwortliche ist, sofern nicht anders angegeben, der Eigent\u00fcmer dieser Anwendung.<\/p>\n<h4>Diese Anwendung<\/h4>\n<p>Das Hardware- oder Softwaretool, mit dem die personenbezogenen Daten der Nutzer gesammelt und verarbeitet werden.<\/p>\n<h4>Dienst<\/h4>\n<p>Der durch diese Anwendung bereitgestellte Dienst, wie in den entsprechenden Bedingungen (falls vorhanden) auf dieser Website\/Anwendung definiert.<\/p>\n<h4>Europ\u00e4ische Union (oder EU)<\/h4>\n<p>Sofern nicht anders angegeben, gilt jede Bezugnahme in diesem Dokument auf die Europ\u00e4ische Union als Bezugnahme auf alle derzeitigen Mitgliedstaaten der Europ\u00e4ischen Union und des Europ\u00e4ischen Wirtschaftsraums.<\/p>\n<h4>Cookies<\/h4>\n<p>Cookies sind Tracking-Tools, die aus kleinen Datenmengen bestehen, die im Browser des Nutzers gespeichert werden.<\/p>\n<h4>Tracking-Tool<\/h4>\n<p>Ein Tracking-Tool ist jede Technologie &#8211; z. B. Cookies, eindeutige Kennungen, Web-Beacons, eingebettete Skripte, E-Tags und Fingerabdr\u00fccke -, die es erm\u00f6glicht, den Nutzer zu verfolgen, beispielsweise durch das Sammeln oder Speichern von Informationen auf dem Ger\u00e4t des Nutzers.<\/p>\n<hr \/>\n<h4>Rechtliche Hinweise<\/h4>\n<p>Sofern nicht anders angegeben, bezieht sich diese Datenschutzrichtlinie ausschlie\u00dflich auf diese Anwendung.<\/p>\n<p><a href=\"https:\/\/www.iubenda.com\/it\/cookie-solution\">iubenda<\/a> hostet diese Inhalte und erhebt nur die f\u00fcr ihre Bereitstellung <a href=\"https:\/\/www.iubenda.com\/privacy-policy\/19418041\">unbedingt erforderlichen personenbezogenen Daten<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_margin=&#8220;default&#8220; bg_image=&#8220;3693&#8243; bg_position=&#8220;center center&#8220; bg_repeat=&#8220;no-repeat&#8220; bg_color=&#8220;#333333&#8243; scene_position=&#8220;center&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; top_padding=&#8220;23%&#8220; bottom_padding=&#8220;2%&#8220; color_overlay=&#8220;#161616&#8243; overlay_strength=&#8220;0.5&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; video_mute=&#8220;true&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243;&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":75,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6328","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cookie policy von GRUBER Logistics S.p.A.<\/title>\n<meta name=\"description\" content=\"Cookie policy - GRUBER Logistics S.p.A.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie policy von GRUBER Logistics S.p.A.\" \/>\n<meta property=\"og:description\" content=\"Cookie policy - GRUBER Logistics S.p.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"GRUBER Logistics S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/it-it.facebook.com\/gruberlogistics\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T12:23:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2025\/02\/GRUBER_Logistics.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GruberLogistics\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/\",\"url\":\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/\",\"name\":\"Cookie policy von GRUBER Logistics S.p.A.\",\"isPartOf\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#website\"},\"datePublished\":\"2019-02-27T13:27:19+00:00\",\"dateModified\":\"2025-04-22T12:23:42+00:00\",\"description\":\"Cookie policy - GRUBER Logistics S.p.A.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gruber-logistics.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#website\",\"url\":\"https:\/\/www.gruber-logistics.com\/de\/\",\"name\":\"GRUBER Logistics S.p.A.\",\"description\":\"Transportunternehmen\",\"publisher\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gruber-logistics.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#organization\",\"name\":\"GRUBER Logistics S.p.A.\",\"url\":\"https:\/\/www.gruber-logistics.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png\",\"contentUrl\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png\",\"width\":324,\"height\":100,\"caption\":\"GRUBER Logistics S.p.A.\"},\"image\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/it-it.facebook.com\/gruberlogistics\/\",\"https:\/\/x.com\/GruberLogistics\",\"https:\/\/www.instagram.com\/gruberlogistics\/\",\"https:\/\/it.linkedin.com\/company\/gruber-logistics\",\"https:\/\/www.youtube.com\/channel\/UCdq3OH0UblNUnUETLsSxLog\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie policy von GRUBER Logistics S.p.A.","description":"Cookie policy - GRUBER Logistics S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/","og_locale":"de_DE","og_type":"article","og_title":"Cookie policy von GRUBER Logistics S.p.A.","og_description":"Cookie policy - GRUBER Logistics S.p.A.","og_url":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/","og_site_name":"GRUBER Logistics S.p.A.","article_publisher":"https:\/\/it-it.facebook.com\/gruberlogistics\/","article_modified_time":"2025-04-22T12:23:42+00:00","og_image":[{"width":1920,"height":1357,"url":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2025\/02\/GRUBER_Logistics.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@GruberLogistics","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/","url":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/","name":"Cookie policy von GRUBER Logistics S.p.A.","isPartOf":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#website"},"datePublished":"2019-02-27T13:27:19+00:00","dateModified":"2025-04-22T12:23:42+00:00","description":"Cookie policy - GRUBER Logistics S.p.A.","breadcrumb":{"@id":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruber-logistics.com\/de\/cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gruber-logistics.com\/de\/"},{"@type":"ListItem","position":2,"name":"Cookie policy"}]},{"@type":"WebSite","@id":"https:\/\/www.gruber-logistics.com\/de\/#website","url":"https:\/\/www.gruber-logistics.com\/de\/","name":"GRUBER Logistics S.p.A.","description":"Transportunternehmen","publisher":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruber-logistics.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gruber-logistics.com\/de\/#organization","name":"GRUBER Logistics S.p.A.","url":"https:\/\/www.gruber-logistics.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png","contentUrl":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png","width":324,"height":100,"caption":"GRUBER Logistics S.p.A."},"image":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it-it.facebook.com\/gruberlogistics\/","https:\/\/x.com\/GruberLogistics","https:\/\/www.instagram.com\/gruberlogistics\/","https:\/\/it.linkedin.com\/company\/gruber-logistics","https:\/\/www.youtube.com\/channel\/UCdq3OH0UblNUnUETLsSxLog"]}]}},"_links":{"self":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/pages\/6328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/comments?post=6328"}],"version-history":[{"count":7,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/pages\/6328\/revisions"}],"predecessor-version":[{"id":26398,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/pages\/6328\/revisions\/26398"}],"wp:attachment":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/media?parent=6328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}