{"id":20936,"date":"2022-12-14T12:54:42","date_gmt":"2022-12-14T12:54:42","guid":{"rendered":"https:\/\/www.gruber-logistics.com\/cambio-ai-vertici-di-zust-bachmeier-dusseldorf\/"},"modified":"2024-06-05T07:46:32","modified_gmt":"2024-06-05T07:46:32","slug":"wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf","status":"publish","type":"post","link":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/","title":{"rendered":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &#038; Bachmeier D\u00fcsseldorf"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<h2>Wechsel in der F\u00fchrungsspitze von Z\u00fcst &amp; Bachmeier D\u00fcsseldorf<b><\/b><\/h2>\n<p>&nbsp;<\/p>\n<p>Mit Wirkung zum 1. Oktober 2022 hat Marcel Gro\u00df die Leitung der Z\u00fcst &amp; Bachmeier-Niederlassung in D\u00fcsseldorf \u00fcbernommen. Er folgt auf Hans Unger, der seinem Team bis Ende des Jahres noch beratend zur Seite stehen und anschlie\u00dfend in den wohlverdienten Ruhestand wechseln wird. Wir haben die beiden zum F\u00fchrungswechsel interviewt.<\/p>\n<p><strong>Herr Unger, wie lange sind Sie bereits bei Z\u00fcst &amp; Bachmeier in D\u00fcsseldorf t\u00e4tig und welche Meilensteine haben die Entwicklung der Niederlassung gepr\u00e4gt?<\/strong><\/p>\n<p>Hans Unger: Ich habe die Niederlassung D\u00fcsseldorf von Anfang an begleitet. Als wir den Standort im Juni 2004 er\u00f6ffneten, waren wir zu dritt. Heute sind wir zehn Kolleginnen und Kollegen. Vor drei Jahren haben wir gr\u00f6\u00dfere R\u00e4umlichkeiten bezogen und den Universal Transport-Standort K\u00f6ln unter unserem Dach integriert, um Kompetenzen zu b\u00fcndeln und Prozesse zu optimieren. Wir haben uns in meiner Zeit aber nicht nur personell, sondern auch gesch\u00e4ftlich gut entwickelt. Selbst in herausfordernden Zeiten wie in der Wirtschaftskrise 2008\/2009 oder w\u00e4hrend der Corona-Pandemie 2020\/2021 konnten wir eine best\u00e4ndige Auftragslage halten. Ein spezieller Fokus unserer T\u00e4tigkeiten liegt auf S\u00fcdostasien, wo wir unter anderem Projekte f\u00fcr den Energiesektor \u00fcbernehmen.<\/p>\n<p><strong>Was waren Ihre besonderen Highlights in den vergangenen 18 Jahren?<\/strong><\/p>\n<p>Hans Unger: Das Gr\u00f6\u00dfte, was wir jemals verladen haben, war eine komplette Gasbohrinsel. Die unterschiedlichsten Baumaterialen und -elemente, darunter zum Beispiel 120.000 Tonnen Rohre, wurden von uns von Herstellern weltweit abgeholt und ins Einsatzgebiet im Kaspischen Meer vor der K\u00fcste Turkmenistans transportiert. Je nach Streckenabschnitt und Transportgut per Stra\u00dfe, Schiene und nat\u00fcrlich Charterschiff.<\/p>\n<p><strong>Herr Gro\u00df, wenn Sie dies h\u00f6ren, freuen Sie sich auf Ihre neue Aufgabe?<\/strong><\/p>\n<p>Marcel Gro\u00df: Sehr. Mir ist aber auch klar, dass ich erst einmal in die Fu\u00dfstapfen von Hans Unger hineinwachen muss. Er hat in den vergangenen Jahren gemeinsam mit dem Team hier sehr viel erreicht und aufgebaut. Ich durfte dies selbst mit begleiten und von ihm lernen. 2009 habe ich bei Z\u00fcst &amp; Bachmeier meine Ausbildung aufgenommen. Damals musste noch mein Vater den Ausbildungsvertrag unterschreiben, weil ich unter 18 war. Danach ging es stetig voran. Vor dem Wechsel in die Niederlassungsleitung war ich als Senior Projektmanager t\u00e4tig.<\/p>\n<p><strong>Welche Aufgaben umfasst Ihre neue Position und haben Sie sich bereits Ziele gesetzt, die Sie in den kommenden Jahren umsetzen m\u00f6chten?<\/strong><\/p>\n<p>Marcel Gro\u00df: Ich habe bereits einige Pl\u00e4ne, wie wir die Niederlassung weiterentwickeln k\u00f6nnen. Dies erfolgt aber immer auch in enger Zusammenarbeit mit dem Team. Wir arbeiten hier mit sehr flachen Hierarchien und unterst\u00fctzen uns gegenseitig. Generell trage ich als Niederlassungsleiter aber die Verantwortung und berichte an die Gesch\u00e4ftsf\u00fchrung der Gruppe. Meine aktuellen Schwerpunkte liegen zum einen in den USA, wo wir bereits jetzt regelm\u00e4\u00dfiges Gesch\u00e4ft haben, das ich perspektivisch ausbauen m\u00f6chte, und zum anderen in der T\u00fcrkei, die mir sehr am Herzen liegt. Um die Aktivit\u00e4ten dort zu erweitern, haben wir sogar ein neues Teammitglied eingestellt.<\/p>\n<p>Hans Unger: Ich m\u00f6chte abschlie\u00dfend noch sagen, dass ich sehr gerne hier gearbeitet habe. Ich freue mich jetzt aber auch darauf, mehr Zeit f\u00fcr ehrenamtliches Engagement zu haben, Reisen mit meiner Frau zu unternehmen und noch einmal die eine oder andere neue Sprache zu lernen. Ich denke, jetzt ist genau der richtige Zeitpunkt f\u00fcr den Wechsel an der Spitze. Nach 18 Jahren haben sich viele Dinge eingeschliffen, aber die Zeiten \u00e4ndern sich und bestimmte Abl\u00e4ufe k\u00f6nnen anders vielleicht besser gestaltet werden. Marcel Gro\u00df wird mit frischem Blick die Dinge bewerten und unser Team am Standort D\u00fcsseldorf in die Zukunft f\u00fchren. Ich w\u00fcnsche ihm daf\u00fcr viel Erfolg!<\/p>\n<p>+++<\/p>\n<p>Die Universal Transport Gruppe bedankt sich bei Hans Unger f\u00fcr sein Engagement und seine herausragende Leistung \u00fcber beinahe zwei Jahrzehnte, mit denen er ma\u00dfgeblich zum Erfolg des Unternehmens beigetragen hat. Wir w\u00fcnschen ihm f\u00fcr den neuen Lebensabschnitt alles Gute!<\/p>\n<p>Dar\u00fcber hinaus begr\u00fc\u00dfen wir Marcel Gro\u00df in seiner neuen Position. Wir freuen uns auf die weitere Zusammenarbeit und w\u00fcnschen ihm ebenfalls viel Erfolg bei seinen alten und neuen Aufgaben![\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][nectar_cascading_images image_1_offset_x_sign=&#8220;+&#8220; image_1_offset_x=&#8220;0%&#8220; image_1_offset_y_sign=&#8220;+&#8220; image_1_offset_y=&#8220;0%&#8220; image_1_rotate_sign=&#8220;+&#8220; image_1_rotate=&#8220;none&#8220; image_1_scale=&#8220;1&#8243; image_1_animation=&#8220;Fade In&#8220; image_1_box_shadow=&#8220;none&#8220; image_1_padding=&#8220;auto&#8220; image_1_max_width_desktop=&#8220;100%&#8220; image_1_max_width_mobile=&#8220;100%&#8220; image_2_offset_x_sign=&#8220;+&#8220; image_2_offset_x=&#8220;0%&#8220; image_2_offset_y_sign=&#8220;+&#8220; image_2_offset_y=&#8220;0%&#8220; image_2_rotate_sign=&#8220;+&#8220; image_2_rotate=&#8220;none&#8220; image_2_scale=&#8220;1&#8243; image_2_animation=&#8220;Fade In&#8220; image_2_box_shadow=&#8220;none&#8220; image_2_padding=&#8220;auto&#8220; image_2_max_width_desktop=&#8220;100%&#8220; image_2_max_width_mobile=&#8220;100%&#8220; image_3_offset_x_sign=&#8220;+&#8220; image_3_offset_x=&#8220;0%&#8220; image_3_offset_y_sign=&#8220;+&#8220; image_3_offset_y=&#8220;0%&#8220; image_3_rotate_sign=&#8220;+&#8220; image_3_rotate=&#8220;none&#8220; image_3_scale=&#8220;1&#8243; image_3_animation=&#8220;Fade In&#8220; image_3_box_shadow=&#8220;none&#8220; image_3_padding=&#8220;auto&#8220; image_3_max_width_desktop=&#8220;100%&#8220; image_3_max_width_mobile=&#8220;100%&#8220; image_4_offset_x_sign=&#8220;+&#8220; image_4_offset_x=&#8220;0%&#8220; image_4_offset_y_sign=&#8220;+&#8220; image_4_offset_y=&#8220;0%&#8220; image_4_rotate_sign=&#8220;+&#8220; image_4_rotate=&#8220;none&#8220; image_4_scale=&#8220;1&#8243; image_4_animation=&#8220;Fade In&#8220; image_4_box_shadow=&#8220;none&#8220; image_4_padding=&#8220;auto&#8220; image_4_max_width_desktop=&#8220;100%&#8220; image_4_max_width_mobile=&#8220;100%&#8220; border_radius=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_link_target=&#8220;_self&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; overlay_strength=&#8220;0.3&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]&#8230;<\/p>\n","protected":false},"author":20,"featured_media":20930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[269],"tags":[],"class_list":{"0":"post-20936","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news-de"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wechsel in der F\u00fchrungsspitze von Z\u00fcst &amp; Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.<\/title>\n<meta name=\"description\" content=\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &amp; Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &amp; Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.\" \/>\n<meta property=\"og:description\" content=\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &amp; Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\" \/>\n<meta property=\"og:site_name\" content=\"GRUBER Logistics S.p.A.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/it-it.facebook.com\/gruberlogistics\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T12:54:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-05T07:46:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GRUBER Logistics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GruberLogistics\" \/>\n<meta name=\"twitter:site\" content=\"@GruberLogistics\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"GRUBER Logistics\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\"},\"author\":{\"name\":\"GRUBER Logistics\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/person\/4e9ceb4fde2258e3923fde9749a69ff8\"},\"headline\":\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &#038; Bachmeier D\u00fcsseldorf\",\"datePublished\":\"2022-12-14T12:54:42+00:00\",\"dateModified\":\"2024-06-05T07:46:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\"},\"wordCount\":1062,\"publisher\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg\",\"articleSection\":[\"News DE\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\",\"url\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\",\"name\":\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.\",\"isPartOf\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg\",\"datePublished\":\"2022-12-14T12:54:42+00:00\",\"dateModified\":\"2024-06-05T07:46:32+00:00\",\"description\":\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage\",\"url\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg\",\"contentUrl\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Z\u00fcst & Bachmeier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gruber-logistics.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &#038; Bachmeier D\u00fcsseldorf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#website\",\"url\":\"https:\/\/www.gruber-logistics.com\/de\/\",\"name\":\"GRUBER Logistics S.p.A.\",\"description\":\"Transportunternehmen\",\"publisher\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gruber-logistics.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#organization\",\"name\":\"GRUBER Logistics S.p.A.\",\"url\":\"https:\/\/www.gruber-logistics.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png\",\"contentUrl\":\"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png\",\"width\":324,\"height\":100,\"caption\":\"GRUBER Logistics S.p.A.\"},\"image\":{\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/it-it.facebook.com\/gruberlogistics\/\",\"https:\/\/x.com\/GruberLogistics\",\"https:\/\/www.instagram.com\/gruberlogistics\/\",\"https:\/\/it.linkedin.com\/company\/gruber-logistics\",\"https:\/\/www.youtube.com\/channel\/UCdq3OH0UblNUnUETLsSxLog\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/person\/4e9ceb4fde2258e3923fde9749a69ff8\",\"name\":\"GRUBER Logistics\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3000cf3662ac8474a82f293beb1cbaa2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3000cf3662ac8474a82f293beb1cbaa2?s=96&d=mm&r=g\",\"caption\":\"GRUBER Logistics\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.","description":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/","og_locale":"de_DE","og_type":"article","og_title":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.","og_description":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.","og_url":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/","og_site_name":"GRUBER Logistics S.p.A.","article_publisher":"https:\/\/it-it.facebook.com\/gruberlogistics\/","article_published_time":"2022-12-14T12:54:42+00:00","article_modified_time":"2024-06-05T07:46:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg","type":"image\/jpeg"}],"author":"GRUBER Logistics","twitter_card":"summary_large_image","twitter_creator":"@GruberLogistics","twitter_site":"@GruberLogistics","twitter_misc":{"Verfasst von":"GRUBER Logistics","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#article","isPartOf":{"@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/"},"author":{"name":"GRUBER Logistics","@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/person\/4e9ceb4fde2258e3923fde9749a69ff8"},"headline":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &#038; Bachmeier D\u00fcsseldorf","datePublished":"2022-12-14T12:54:42+00:00","dateModified":"2024-06-05T07:46:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/"},"wordCount":1062,"publisher":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#organization"},"image":{"@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg","articleSection":["News DE"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/","url":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/","name":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.","isPartOf":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage"},"image":{"@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg","datePublished":"2022-12-14T12:54:42+00:00","dateModified":"2024-06-05T07:46:32+00:00","description":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst & Bachmeier D\u00fcsseldorf - GRUBER Logistics S.p.A.","breadcrumb":{"@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#primaryimage","url":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg","contentUrl":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2024\/01\/Z_B_Ddorf_div-8-1280x720-1.jpg","width":1280,"height":720,"caption":"Z\u00fcst & Bachmeier"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruber-logistics.com\/de\/wechsel-in-der-fuehrungsspitze-von-zuest-bachmeier-duesseldorf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gruber-logistics.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wechsel in der F\u00fchrungsspitze von Z\u00fcst &#038; Bachmeier D\u00fcsseldorf"}]},{"@type":"WebSite","@id":"https:\/\/www.gruber-logistics.com\/de\/#website","url":"https:\/\/www.gruber-logistics.com\/de\/","name":"GRUBER Logistics S.p.A.","description":"Transportunternehmen","publisher":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruber-logistics.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gruber-logistics.com\/de\/#organization","name":"GRUBER Logistics S.p.A.","url":"https:\/\/www.gruber-logistics.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png","contentUrl":"https:\/\/www.gruber-logistics.com\/wp-content\/uploads\/2018\/11\/Gruber-logistics-logo-color.png","width":324,"height":100,"caption":"GRUBER Logistics S.p.A."},"image":{"@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/it-it.facebook.com\/gruberlogistics\/","https:\/\/x.com\/GruberLogistics","https:\/\/www.instagram.com\/gruberlogistics\/","https:\/\/it.linkedin.com\/company\/gruber-logistics","https:\/\/www.youtube.com\/channel\/UCdq3OH0UblNUnUETLsSxLog"]},{"@type":"Person","@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/person\/4e9ceb4fde2258e3923fde9749a69ff8","name":"GRUBER Logistics","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruber-logistics.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3000cf3662ac8474a82f293beb1cbaa2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3000cf3662ac8474a82f293beb1cbaa2?s=96&d=mm&r=g","caption":"GRUBER Logistics"}}]}},"_links":{"self":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/posts\/20936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/comments?post=20936"}],"version-history":[{"count":1,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/posts\/20936\/revisions"}],"predecessor-version":[{"id":20939,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/posts\/20936\/revisions\/20939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/media\/20930"}],"wp:attachment":[{"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/media?parent=20936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/categories?post=20936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruber-logistics.com\/de\/wp-json\/wp\/v2\/tags?post=20936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}